{"id":5,"date":"2024-03-15T13:51:14","date_gmt":"2024-03-15T13:51:14","guid":{"rendered":"https:\/\/phuketworldprosupply.com\/?page_id=5"},"modified":"2024-10-05T08:29:36","modified_gmt":"2024-10-05T08:29:36","slug":"home","status":"publish","type":"page","link":"https:\/\/phuketworldprosupply.com\/","title":{"rendered":"Home"},"content":{"rendered":"\n\n\t<section class=\"section\" id=\"section_2120911559\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-1434131076\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n\n  <div class=\"banner has-hover\" id=\"banner-420854346\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/PhuketWorldProSupply_4-2.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1120088759\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2>Phuket World Pro Supply<\/h2>\n<h3>Design and produce products for use in hotels<\/h3>\n<p>Leading designer and distributor of hotel supplies in Thailand. For nearly 10 years, we&#8217;ve provided custom amenities and luxurious leather wear to prestigious hotels in Phuket, Khao Lak, Phang Nga, Krabi, and Samui. We deliver exceptional service and products to create unique, recognizable themes for your business.<\/p>\n<a class=\"button secondary is-larger\"  >\n\t\t<span>contact now<\/span>\n\t<\/a>\n\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1120088759 {\n  width: 66%;\n}\n#text-box-1120088759 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-420854346 {\n  padding-top: 500px;\n}\n#banner-420854346 .banner-bg img {\n  object-position: 38% 63%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-544674737\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_9521-scaled.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1706753649\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2>Phuket World Pro Supply<\/h2>\n<h3>Design and produce products for use in hotels<\/h3>\n<p>Leading designer and distributor of hotel supplies in Thailand. For nearly 10 years, we&#8217;ve provided custom amenities and luxurious leather wear to prestigious hotels in Phuket, Khao Lak, Phang Nga, Krabi, and Samui. We deliver exceptional service and products to create unique, recognizable themes for your business.<\/p>\n<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/contact-us\/\" class=\"button secondary is-larger\"  >\n\t\t<span>contact now<\/span>\n\t<\/a>\n\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1706753649 {\n  width: 64%;\n}\n#text-box-1706753649 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-544674737 {\n  padding-top: 500px;\n}\n#banner-544674737 .banner-bg img {\n  object-position: 33% 38%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-1748814966\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_9570-scaled.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-209915993\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-209915993 {\n  width: 60%;\n}\n#text-box-209915993 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1748814966 {\n  padding-top: 500px;\n}\n#banner-1748814966 .banner-bg img {\n  object-position: 70% 27%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-1827995224\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_9555-scaled.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-596144079\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-596144079 {\n  width: 60%;\n}\n#text-box-596144079 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1827995224 {\n  padding-top: 500px;\n}\n#banner-1827995224 .banner-bg img {\n  object-position: 49% 57%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-493368854\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Resin_05.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-355154418\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-355154418 {\n  width: 60%;\n}\n#text-box-355154418 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-493368854 {\n  padding-top: 500px;\n}\n#banner-493368854 .banner-bg img {\n  object-position: 19% 72%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-489078343\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/DryAmenity_01.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-840807676\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-840807676 {\n  width: 60%;\n}\n#text-box-840807676 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-489078343 {\n  padding-top: 500px;\n}\n#banner-489078343 .banner-bg img {\n  object-position: 54% 31%;\n}\n<\/style>\n  <\/div>\n\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n<div class=\"row row-small align-equal align-center\"  id=\"row-1971532321\">\n\n\n\t<div id=\"col-1649917717\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 74px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e0a\u0e37\u0e48\u0e2d-15-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e0a\u0e37\u0e48\u0e2d-15-300x300.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e0a\u0e37\u0e48\u0e2d-15-150x150.png 150w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e0a\u0e37\u0e48\u0e2d-15.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"gap-1976964253\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1976964253 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-2499924030\" class=\"text\">\n\t\t\n\n<h2>High Quality Products<\/h2>\n\t\t\n<style>\n#text-2499924030 {\n  font-size: 0.9rem;\n  color: rgb(255,255,255);\n}\n#text-2499924030 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1378983830\" class=\"text\">\n\t\t\n\n\n\t\t\n<style>\n#text-1378983830 {\n  text-align: center;\n  color: rgb(255,255,255);\n}\n#text-1378983830 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1023580273\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 74px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e0a\u0e37\u0e48\u0e2d-16-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e0a\u0e37\u0e48\u0e2d-16-300x300.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e0a\u0e37\u0e48\u0e2d-16-150x150.png 150w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e0a\u0e37\u0e48\u0e2d-16.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"gap-902931669\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-902931669 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-769698415\" class=\"text\">\n\t\t\n\n<h2>10 Years of Experience<\/h2>\n\t\t\n<style>\n#text-769698415 {\n  font-size: 0.9rem;\n  text-align: left;\n  color: rgb(255,255,255);\n}\n#text-769698415 > * {\n  color: rgb(255,255,255);\n}\n@media (min-width:550px) {\n  #text-769698415 {\n    text-align: center;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-251759281\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1483360261\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1483360261 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 46px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/1-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/1-300x300.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/1-150x150.png 150w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/1.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<a href=\"tel:+6676688985\" class=\"button secondary is-larger\"  >\n\t\t<span>+66 76688985<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2120911559 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: #2a74b8;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1362152256\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"696\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/06\/bg-pws.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-2015618209\">\n\n\n\t<div id=\"col-23665784\" class=\"col medium-11 small-12 large-11\"  data-animate=\"bounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1405964387\" class=\"text\">\n\t\t\n\n<p>\u00a0<\/p>\n<h3>WELCOME TO<\/h3>\n\t\t\n<style>\n#text-1405964387 {\n  color: #1c4f8c;\n}\n#text-1405964387 > * {\n  color: #1c4f8c;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2189863260\" class=\"text\">\n\t\t\n\n<h1>Phuket World Pro Supply<\/h1>\n\t\t\n<style>\n#text-2189863260 {\n  font-size: 1.75rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<p><strong>Phuket World Pro Supply Co., Ltd.<\/strong> is one of the major distributors of hotels, resorts, cruise, and hospital accessories in Thailand. As a leading designer and manufacturer of complete hotel supplies, we cater to the needs of some of the most prestigious hotels in the region. Our professional team has been providing excellent service and products to our clients for nearly 10 years, bringing your ideas to life and helping you create the perfect theme and design to fit your business.<\/p>\n<p>We specialize in custom amenities and luxurious leather wear, ensuring that every product we offer symbolizes your business while having its own recognizable identity. Whether you need a bespoke amenities kit, high-quality leather wear, or any other hotel supplies, we have the expertise to deliver exactly what you need.<\/p>\n<p>Phuket World Pro Supply Co., Ltd. proudly serves key areas including <strong>Phuket, Khao Lak, Phang Nga, Krabi, and Samui.<\/strong> Our commitment to excellence and attention to detail make us the preferred choice for <strong>hotel supplies, hotel amenities, and amenity kits<\/strong> in the region.<\/p>\n\t<div id=\"gap-2058572026\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2058572026 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/about-us-2\/\" class=\"button primary\"  >\n\t\t<span>Read more<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-23665784 > .col-inner {\n  padding: 50px 0px 25px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-38331516\" class=\"col large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-2144720847\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n\n  <div class=\"banner has-hover\" id=\"banner-1839717139\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/inroom_16.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1881710051\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1881710051 {\n  width: 60%;\n}\n#text-box-1881710051 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1839717139 {\n  padding-top: 500px;\n}\n#banner-1839717139 .banner-bg img {\n  object-position: 0% 85%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-654177330\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/inroom_05-1.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-190586743\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-190586743 {\n  width: 60%;\n}\n#text-box-190586743 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-654177330 {\n  padding-top: 500px;\n}\n#banner-654177330 .banner-bg img {\n  object-position: 0% 69%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-757692609\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2347-1-scaled.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-751876334\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-751876334 {\n  width: 60%;\n}\n#text-box-751876334 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-757692609 {\n  padding-top: 500px;\n}\n#banner-757692609 .banner-bg img {\n  object-position: 0% 31%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-269740147\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/inroom_04-1.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-2030242984\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-2030242984 {\n  width: 60%;\n}\n#text-box-2030242984 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-269740147 {\n  padding-top: 500px;\n}\n#banner-269740147 .banner-bg img {\n  object-position: 0% 51%;\n}\n<\/style>\n  <\/div>\n\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1362152256 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1533418997\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t<div id=\"gap-1042682286\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1042682286 {\n  padding-top: 15px;\n}\n@media (min-width:550px) {\n  #gap-1042682286 {\n    padding-top: 100px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-2252750268\" class=\"text\">\n\t\t\n\n<h4>Your Ideas, Make Reality<\/h4>\n\t\t\n<style>\n#text-2252750268 {\n  text-align: center;\n  color: #1c4f8c;\n}\n#text-2252750268 > * {\n  color: #1c4f8c;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-center\" style=\"max-width:1300px\" id=\"row-1240988355\">\n\n\n\t<div id=\"col-1308668651\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h1 class=\"uppercase\"><span style=\"font-size: 170%;\">Custom your product<\/span><\/h1>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1308668651 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1415121762\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1317735201\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1317735201 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/custom\/\" class=\"button primary\"  style=\"padding:5px 25px 5px 25px;\">\n\t\t<span>Let's custom your product<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1415121762 > .col-inner {\n  padding: 0px 0px -10px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small row-full-width\"  id=\"row-1175004393\">\n\n\n\t<div id=\"col-987090521\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row row-small\"  id=\"row-1740930092\">\n\n\n\t<div id=\"col-1217982484\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:240px;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/PhuketWorldProSupply_3.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/PhuketWorldProSupply_3.jpg 1920w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/PhuketWorldProSupply_3-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/PhuketWorldProSupply_3-1024x683.jpg 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/PhuketWorldProSupply_3-768x512.jpg 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/PhuketWorldProSupply_3-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"gap-401266497\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-401266497 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:240px;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/DryAmenity_01.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/DryAmenity_01.jpg 800w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/DryAmenity_01-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/DryAmenity_01-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1445209885\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:500px;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2859-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2859-scaled.jpg 1707w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2859-200x300.jpg 200w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2859-683x1024.jpg 683w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2859-768x1152.jpg 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2859-1024x1536.jpg 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2859-1365x2048.jpg 1365w\" sizes=\"auto, (max-width: 1707px) 100vw, 1707px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1943063829\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row row-small\"  id=\"row-1685807969\">\n\n\n\t<div id=\"col-381166972\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:240px;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/\u0e40\u0e23\u0e0b\u0e34\u0e48\u0e19-The-priva-9-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/\u0e40\u0e23\u0e0b\u0e34\u0e48\u0e19-The-priva-9-scaled.jpg 2560w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/\u0e40\u0e23\u0e0b\u0e34\u0e48\u0e19-The-priva-9-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/\u0e40\u0e23\u0e0b\u0e34\u0e48\u0e19-The-priva-9-1024x683.jpg 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/\u0e40\u0e23\u0e0b\u0e34\u0e48\u0e19-The-priva-9-768x512.jpg 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/\u0e40\u0e23\u0e0b\u0e34\u0e48\u0e19-The-priva-9-1536x1024.jpg 1536w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/\u0e40\u0e23\u0e0b\u0e34\u0e48\u0e19-The-priva-9-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-714417509\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:240px;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2347-1-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2347-1-scaled.jpg 2560w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2347-1-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2347-1-1024x683.jpg 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2347-1-768x512.jpg 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2347-1-1536x1024.jpg 1536w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2347-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-599351402\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:240px;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/inroom_04-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/inroom_04-1.jpg 800w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/inroom_04-1-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/inroom_04-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1533418997 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_1533418997 .section-bg-overlay {\n  background-color: rgba(255,255,255,.5);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row align-center\" style=\"max-width:1300px\" id=\"row-1041047211\">\n\n\n\t<div id=\"col-899959492\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1921498588\" class=\"text\">\n\t\t\n\n<p>\u00a0<\/p>\n<h6>PHUEKT WORLD PRO SUPPLY<\/h6>\n\t\t\n<style>\n#text-1921498588 {\n  text-align: center;\n  color: #1c4f8c;\n}\n#text-1921498588 > * {\n  color: #1c4f8c;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-403260894\" class=\"text\">\n\t\t\n\n<h1>Our Products<\/h1>\n\t\t\n<style>\n#text-403260894 {\n  font-size: 1.75rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1477669286\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1477669286 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small row-full-width\"  id=\"row-64597876\">\n\n\n\t<div id=\"col-1094497937\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1724839986\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/PhuketWorldProSupply_3.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/PhuketWorldProSupply_3.jpg 1920w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/PhuketWorldProSupply_3-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/PhuketWorldProSupply_3-1024x683.jpg 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/PhuketWorldProSupply_3-768x512.jpg 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/PhuketWorldProSupply_3-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1724839986 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h2 class=\"text-uppercase g-mb-10 font-weight-semibold\"><span class=\"text-primary\">INROOM <\/span>\u00a0ESSENTAILS<\/h2>\n<a data-animate=\"bounceIn\" href=\"https:\/\/phuketworldprosupply.com\/index.php\/product\/inroom-essential\/\" class=\"button primary\"  style=\"border-radius:99px;\">\n\t\t<span>More info<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1317044390\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2099613674\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Resin_07.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Resin_07.jpg 800w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Resin_07-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Resin_07-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2099613674 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h2 class=\"text-uppercase g-mb-10 font-weight-semibold\"><span class=\"text-primary\">BATHROOM <\/span>AMENITY<\/h2>\n<a data-animate=\"bounceIn\" href=\"https:\/\/phuketworldprosupply.com\/index.php\/product\/bathroom-amenity\/\" class=\"button primary\"  style=\"border-radius:99px;\">\n\t\t<span>More info<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1461529863\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_353873982\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1923\" height=\"2560\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/6-scaled.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/6-scaled.jpg 1923w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/6-225x300.jpg 225w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/6-769x1024.jpg 769w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/6-768x1022.jpg 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/6-1154x1536.jpg 1154w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/6-1539x2048.jpg 1539w\" sizes=\"auto, (max-width: 1923px) 100vw, 1923px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_353873982 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h2 class=\"text-uppercase g-mb-10 font-weight-semibold\"><span class=\"text-primary\">FOOD &amp;<\/span>\u00a0BEVERAGE<\/h2>\n<a data-animate=\"bounceIn\" href=\"https:\/\/phuketworldprosupply.com\/index.php\/product\/food-and-beverage\/\" class=\"button primary\"  style=\"border-radius:99px;\">\n\t\t<span>More info<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1147408558\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1995987154\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2606.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2606.jpg 2048w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2606-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2606-1024x683.jpg 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2606-768x512.jpg 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/05\/IMG_2606-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1995987154 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h2 class=\"text-uppercase g-mb-10 font-weight-semibold\"><span class=\"text-primary\">OTHER<\/span><\/h2>\n<a data-animate=\"bounceIn\" href=\"https:\/\/phuketworldprosupply.com\/index.php\/product\/other\/\" class=\"button primary\"  style=\"border-radius:99px;\">\n\t\t<span>More info<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-1319945420\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1319945420 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"gap-550496373\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-550496373 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section\" id=\"section_174675832\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1583490829\">\n\n\n\t<div id=\"col-1412985004\" class=\"col medium-6 small-12 large-6\"  data-animate=\"bounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3670562420\" class=\"text\">\n\t\t\n\n<h6>PHUKET WORLD PRO SUPPLY<\/h6>\n\t\t\n<style>\n#text-3670562420 {\n  font-size: 0.9rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1088874936\" class=\"text\">\n\t\t\n\n<h1><span class=\"Y2IQFc\" lang=\"en\">Examples of products<\/span><\/h1>\n\t\t\n<style>\n#text-1088874936 {\n  font-size: 1.75rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1412985004 > .col-inner {\n  padding: 50px 0px 50px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1676546985\">\n\n\n\t<div id=\"col-30749756\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Resin_07.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Resin_07.jpg 800w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Resin_07-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Resin_07-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/resin\/\" class=\"button primary is-underline\"  >\n\t\t<span>more detail<\/span>\n\t<\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-435272263\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/DryAmenity_12.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/DryAmenity_12.jpg 800w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/DryAmenity_12-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/DryAmenity_12-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/amennities-custom\/\" class=\"button primary is-underline\"  >\n\t\t<span>more detail<\/span>\n\t<\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2040429185\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_2625-scaled.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_2625-scaled.jpg 2560w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_2625-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_2625-1024x683.jpg 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_2625-768x512.jpg 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_2625-1536x1024.jpg 1536w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_2625-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/wood\/\" class=\"button primary is-underline\"  >\n\t\t<span>more detail<\/span>\n\t<\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1597553517\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/InRoom_10.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/InRoom_10.jpg 800w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/InRoom_10-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/InRoom_10-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/leather-wear\/\" class=\"button primary is-underline\"  >\n\t\t<span>more detail<\/span>\n\t<\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1685583092\">\n\n\n\t<div id=\"col-727220695\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/InRoom_08.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/InRoom_08.jpg 800w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/InRoom_08-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/InRoom_08-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/leather-wear\/\" class=\"button primary is-underline\"  >\n\t\t<span>more detail<\/span>\n\t<\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1013964965\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/DryAmenity_04.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/DryAmenity_04.jpg 800w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/DryAmenity_04-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/DryAmenity_04-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/amennities-custom\/\" class=\"button primary is-underline\"  >\n\t\t<span>more detail<\/span>\n\t<\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-155835160\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Orientalplus1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Orientalplus1.jpg 800w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Orientalplus1-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Orientalplus1-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/product\/food-and-beverage\/\" class=\"button primary is-underline\"  >\n\t\t<span>more detail<\/span>\n\t<\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1956556055\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/InRoom_07.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/InRoom_07.jpg 800w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/InRoom_07-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/InRoom_07-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/wood\/\" class=\"button primary is-underline\"  >\n\t\t<span>more detail<\/span>\n\t<\/a>\n\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_174675832 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(245, 247, 251);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1733392737\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-389480490\">\n\n\n\t<div id=\"col-1039504686\" class=\"col medium-6 small-12 large-6\"  data-animate=\"bounceInDown\">\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2721764842\" class=\"text\">\n\t\t\n\n<h1>Our Client<\/h1>\n\t\t\n<style>\n#text-2721764842 {\n  font-size: 1.75rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1039504686 > .col-inner {\n  padding: 50px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"slider-wrapper relative\" id=\"slider-611193192\" >\n    <div class=\"slider slider-nav-dots-simple slider-nav-circle slider-nav-large slider-nav-dark slider-nav-outside slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 3000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": false,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"row\"  id=\"row-161389169\">\n\n\n\t<div id=\"col-1074708767\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_450035144\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"596\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Novotel-Phuket-Kamala-Beach-Logo-May15-01-1024x598.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Novotel-Phuket-Kamala-Beach-Logo-May15-01-1024x598.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Novotel-Phuket-Kamala-Beach-Logo-May15-01-300x175.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Novotel-Phuket-Kamala-Beach-Logo-May15-01-768x448.png 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Novotel-Phuket-Kamala-Beach-Logo-May15-01.png 1417w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_450035144 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-647823405\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_424565231\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"670\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-galla-hotel-logo-01-1024x673.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-galla-hotel-logo-01-1024x673.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-galla-hotel-logo-01-300x197.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-galla-hotel-logo-01-768x504.png 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-galla-hotel-logo-01-1536x1009.png 1536w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-galla-hotel-logo-01-2048x1345.png 2048w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_424565231 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-593840795\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1846932233\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Rosewood_Trans.gif\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1846932233 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2133775729\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_468869691\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"510\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-bay-01-1024x512.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-bay-01-1024x512.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-bay-01-300x150.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-bay-01-768x384.png 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-bay-01.png 1181w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_468869691 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-51031349\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_513159489\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"510\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-bell-01-1024x512.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-bell-01-1024x512.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-bell-01-300x150.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-bell-01-768x384.png 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-bell-01.png 1181w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_513159489 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-46221658\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1019933616\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"510\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-naiharn-01-1024x512.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-naiharn-01-1024x512.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-naiharn-01-300x150.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-naiharn-01-768x384.png 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-naiharn-01.png 1181w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1019933616 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1834311977\">\n\n\n\t<div id=\"col-1648686849\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1368668166\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"158\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/BYD.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/BYD.png 320w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/BYD-300x148.png 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1368668166 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-135479704\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_92420475\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"392\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/47-Cape-Sienna-Phuket_Logo-620x392-2.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/47-Cape-Sienna-Phuket_Logo-620x392-2.jpg 620w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/47-Cape-Sienna-Phuket_Logo-620x392-2-300x190.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_92420475 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-728098048\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1347112715\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"175\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/logo.jpg\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1347112715 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-50251654\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1979256210\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"393\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/1-e1340363217683.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/1-e1340363217683.png 600w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/1-e1340363217683-300x197.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1979256210 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1437571943\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1808480622\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1181\" height=\"945\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Surin-beach-01.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Surin-beach-01.png 1181w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Surin-beach-01-300x240.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Surin-beach-01-1024x819.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Surin-beach-01-768x615.png 768w\" sizes=\"auto, (max-width: 1181px) 100vw, 1181px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1808480622 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1927751138\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1951755052\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"3508\" height=\"2480\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Impiana-Flag-01.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Impiana-Flag-01.png 3508w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Impiana-Flag-01-300x212.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Impiana-Flag-01-1024x724.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Impiana-Flag-01-768x543.png 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Impiana-Flag-01-1536x1086.png 1536w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Impiana-Flag-01-2048x1448.png 2048w\" sizes=\"auto, (max-width: 3508px) 100vw, 3508px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1951755052 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-735800141\">\n\n\n\t<div id=\"col-228241957\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1870491467\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1181\" height=\"945\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-vijitt-01.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-vijitt-01.png 1181w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-vijitt-01-300x240.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-vijitt-01-1024x819.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-vijitt-01-768x615.png 768w\" sizes=\"auto, (max-width: 1181px) 100vw, 1181px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1870491467 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1069048606\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1267345062\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1181\" height=\"945\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-kee-01.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-kee-01.png 1181w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-kee-01-300x240.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-kee-01-1024x819.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/The-kee-01-768x615.png 768w\" sizes=\"auto, (max-width: 1181px) 100vw, 1181px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1267345062 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1933559016\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1214898882\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1181\" height=\"945\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/My-beach-01.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/My-beach-01.png 1181w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/My-beach-01-300x240.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/My-beach-01-1024x819.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/My-beach-01-768x615.png 768w\" sizes=\"auto, (max-width: 1181px) 100vw, 1181px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1214898882 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1842579696\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1452824835\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2700\" height=\"1590\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/La-Flora-LOGO-01.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/La-Flora-LOGO-01.png 2700w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/La-Flora-LOGO-01-300x177.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/La-Flora-LOGO-01-1024x603.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/La-Flora-LOGO-01-768x452.png 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/La-Flora-LOGO-01-1536x905.png 1536w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/La-Flora-LOGO-01-2048x1206.png 2048w\" sizes=\"auto, (max-width: 2700px) 100vw, 2700px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1452824835 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-952699366\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1786042215\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"3508\" height=\"2480\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/LOGO-THARA-01.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/LOGO-THARA-01.png 3508w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/LOGO-THARA-01-300x212.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/LOGO-THARA-01-1024x724.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/LOGO-THARA-01-768x543.png 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/LOGO-THARA-01-1536x1086.png 1536w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/LOGO-THARA-01-2048x1448.png 2048w\" sizes=\"auto, (max-width: 3508px) 100vw, 3508px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1786042215 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1074668100\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1531095890\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1181\" height=\"945\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/MAYA-01.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/MAYA-01.png 1181w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/MAYA-01-300x240.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/MAYA-01-1024x819.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/MAYA-01-768x615.png 768w\" sizes=\"auto, (max-width: 1181px) 100vw, 1181px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1531095890 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-323563202\">\n\n\n\t<div id=\"col-1475780383\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1326559418\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1903\" height=\"947\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Ramada-Plaza-By-Wyndham-Chao-Fah-01.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Ramada-Plaza-By-Wyndham-Chao-Fah-01.png 1903w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Ramada-Plaza-By-Wyndham-Chao-Fah-01-300x149.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Ramada-Plaza-By-Wyndham-Chao-Fah-01-1024x510.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Ramada-Plaza-By-Wyndham-Chao-Fah-01-768x382.png 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Ramada-Plaza-By-Wyndham-Chao-Fah-01-1536x764.png 1536w\" sizes=\"auto, (max-width: 1903px) 100vw, 1903px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1326559418 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1943922313\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1132124743\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1181\" height=\"591\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/NOOK-DEE-01.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/NOOK-DEE-01.png 1181w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/NOOK-DEE-01-300x150.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/NOOK-DEE-01-1024x512.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/NOOK-DEE-01-768x384.png 768w\" sizes=\"auto, (max-width: 1181px) 100vw, 1181px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1132124743 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-194383843\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1655792330\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"3909\" height=\"2173\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Phuket_4c_G_p_xxxx_i122173-01.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Phuket_4c_G_p_xxxx_i122173-01.png 3909w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Phuket_4c_G_p_xxxx_i122173-01-300x167.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Phuket_4c_G_p_xxxx_i122173-01-1024x569.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Phuket_4c_G_p_xxxx_i122173-01-768x427.png 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Phuket_4c_G_p_xxxx_i122173-01-1536x854.png 1536w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Phuket_4c_G_p_xxxx_i122173-01-2048x1138.png 2048w\" sizes=\"auto, (max-width: 3909px) 100vw, 3909px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1655792330 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-716120970\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1230340494\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"3508\" height=\"1667\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Diamond-resort-01.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Diamond-resort-01.png 3508w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Diamond-resort-01-300x143.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Diamond-resort-01-1024x487.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Diamond-resort-01-768x365.png 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Diamond-resort-01-1536x730.png 1536w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Diamond-resort-01-2048x973.png 2048w\" sizes=\"auto, (max-width: 3508px) 100vw, 3508px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1230340494 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2048764228\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2134937239\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1181\" height=\"591\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Le-menara-01.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Le-menara-01.png 1181w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Le-menara-01-300x150.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Le-menara-01-1024x512.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/Le-menara-01-768x384.png 768w\" sizes=\"auto, (max-width: 1181px) 100vw, 1181px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2134937239 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-160323824\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1721174801\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"5906\" height=\"3150\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/222-01.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/222-01.png 5906w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/222-01-300x160.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/222-01-1024x546.png 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/222-01-768x410.png 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/222-01-1536x819.png 1536w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/222-01-2048x1092.png 2048w\" sizes=\"auto, (max-width: 5906px) 100vw, 5906px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1721174801 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t<div id=\"gap-1111556185\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1111556185 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1733392737 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(245, 247, 251);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1797422759\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-small align-equal row-box-shadow-2-hover\"  id=\"row-778398519\">\n\n\n\t<div id=\"col-1024766300\" class=\"col medium-6 small-12 large-3 col-hover-fade\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 80px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/4-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/4-300x300.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/4-150x150.png 150w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/4.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h3>Planning<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-228777753\" class=\"col medium-6 small-12 large-3 col-hover-fade\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 80px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/5-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/5-300x300.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/5-150x150.png 150w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/5.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h3><span class=\"Y2IQFc\" lang=\"en\">Control costs<\/span><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-774513911\" class=\"col medium-6 small-12 large-3 col-hover-fade\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 80px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/6-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/6-300x300.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/6-150x150.png 150w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/6.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h3>Create value<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-244389824\" class=\"col medium-6 small-12 large-3 col-hover-fade\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 80px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/7-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/7-300x300.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/7-150x150.png 150w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/7.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h3>Service team<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-778398519 > .col > .col-inner {\n  padding: 40px 40px 40px 40px;\n  background-color: rgb(255,255,255);\n  border-radius: 20px;\n}\n<\/style>\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1797422759 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: #2a74b8;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1587692861\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1344815147\">\n\n\n\t<div id=\"col-1482416240\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row row-small row-full-width row-box-shadow-1 row-box-shadow-4-hover\"  id=\"row-115574390\">\n\n\n\t<div id=\"col-8639064\" class=\"col medium-6 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h2><span class=\"count-up\">253<\/span><\/h2>\n<p>Projects<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1078403282\" class=\"col medium-6 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h2><span class=\"count-up\">944<\/span><\/h2>\n<p>Products<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-43794669\" class=\"col medium-6 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h2><span class=\"count-up\">50<\/span><\/h2>\n<p>Events<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1047302591\" class=\"col medium-6 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h2><span class=\"count-up\">500<\/span><\/h2>\n<p>Clients<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-115574390 > .col > .col-inner {\n  padding: 30px 30px 30px 30px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n<\/div>\n\t<div id=\"gap-53298128\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-53298128 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-3550242226\" class=\"text\">\n\t\t\n\n<h1>Blog<\/h1>\n\t\t\n<style>\n#text-3550242226 {\n  font-size: 1.75rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-656720035\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-656720035 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n  \n    <div class=\"row large-columns-3 medium-columns-1 small-columns-1 row-full-width slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/2024\/03\/23\/test-blog-02\/\" class=\"plain\" aria-label=\"Test Blog 02\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_5464-scaled.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_5464-scaled.jpg 2560w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_5464-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_5464-1024x683.jpg 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_5464-768x512.jpg 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_5464-1536x1024.jpg 1536w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_5464-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/2024\/03\/23\/test-blog-02\/\" class=\"plain\">Test Blog 02<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tTitle: &#8220;Embracing Nature: The Timeless Beauty and Eco-Friendliness of Wood&#8221; In a world filled with [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-circle-inside\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">23<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Mar<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/2024\/03\/23\/test\/\" class=\"plain\" aria-label=\"Test Blog 01\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_2615-scaled.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_2615-scaled.jpg 2560w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_2615-300x200.jpg 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_2615-1024x683.jpg 1024w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_2615-768x512.jpg 768w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_2615-1536x1024.jpg 1536w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/03\/IMG_2615-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/2024\/03\/23\/test\/\" class=\"plain\">Test Blog 01<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\thello we just test for a blog\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-circle-inside\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">23<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Mar<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/phuketworldprosupply.com\/index.php\/2024\/03\/04\/hello-world\/\" class=\"plain\">Hello world!<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t<div class=\"post-meta is-small op-8\">March 4, 2024<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tWelcome to WordPress. This is your first post. Edit or delete it, then start writing!\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1587692861 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1439784580\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-middle align-center\" style=\"max-width:700px\" id=\"row-263149025\">\n\n\n\t<div id=\"col-1649833994\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1572425992\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1572425992 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-1175717151\" class=\"text\">\n\t\t\n\n<h1>Contact Us<\/h1>\n\t\t\n<style>\n#text-1175717151 {\n  font-size: 1.75rem;\n  text-align: center;\n  color: rgb(255,255,255);\n}\n#text-1175717151 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1487017055\">\n\n\n\t<div id=\"col-2044167192\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 56px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/3-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/3-300x300.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/3-150x150.png 150w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/3.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-2242424761\" class=\"text\">\n\t\t\n\n<h3>Email<\/h3>\n\t\t\n<style>\n#text-2242424761 {\n  color: rgb(255,255,255);\n}\n#text-2242424761 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-4276697519\" class=\"text\">\n\t\t\n\n<p>info@pwshotelsupply.com<\/p>\n\t\t\n<style>\n#text-4276697519 {\n  text-align: center;\n  color: rgb(255,255,255);\n}\n#text-4276697519 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-611938974\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 56px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/2-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/2-300x300.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/2-150x150.png 150w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/2.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-213202340\" class=\"text\">\n\t\t\n\n<h3>Place<\/h3>\n\t\t\n<style>\n#text-213202340 {\n  color: rgb(255,255,255);\n}\n#text-213202340 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1127127512\" class=\"text\">\n\t\t\n\n<p>100\/516 Moo 5, Rassada,<\/p>\n<p>Muang 83000 Phuket<\/p>\n\t\t\n<style>\n#text-1127127512 {\n  text-align: center;\n  color: rgb(255,255,255);\n}\n#text-1127127512 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1714642512\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/1-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/1-300x300.png 300w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/1-150x150.png 150w, https:\/\/phuketworldprosupply.com\/wp-content\/uploads\/2024\/04\/1.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-2048824631\" class=\"text\">\n\t\t\n\n<h3>Sale Office &amp; Fax<\/h3>\n\t\t\n<style>\n#text-2048824631 {\n  color: rgb(255,255,255);\n}\n#text-2048824631 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n<a href=\"tel:+6676688985\" class=\"button secondary\"  >\n\t\t<span>+66 76688985<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1439784580 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: #2a74b8;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_917374785\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t<div id=\"gap-2036723851\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2036723851 {\n  padding-top: 100px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row row-collapse row-full-width align-middle\"  id=\"row-1040059236\">\n\n\n\t<div id=\"col-886390324\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-349429914\" class=\"text\">\n\t\t\n\n<h1>Get in touch<\/h1>\n\t\t\n<style>\n#text-349429914 {\n  font-size: 1.75rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n<div class='fluentform ff-default fluentform_wrapper_3 ffs_default_wrap'><form data-form_id=\"3\" id=\"fluentform_3\" class=\"frm-fluent-form fluent_form_3 ff-el-form-top ff_form_instance_3_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_3_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Contact Form Demo (#3)<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='1' \/><input type=\"hidden\" id=\"_fluentform_3_fluentformnonce\" name=\"_fluentform_3_fluentformnonce\" value=\"3b824fec19\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/index.php\/wp-json\/wp\/v2\/pages\/5\" \/><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_3_names_first_name_' >First Name<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_3_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"First Name\" aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><div class='ff-t-cell '><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_3_names_last_name_' >Last Name<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" id=\"ff_3_names_last_name_\" class=\"ff-el-form-control\" placeholder=\"Last Name\" aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_3_email' aria-label=\"Email\">Email<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_3_email\" class=\"ff-el-form-control\" placeholder=\"Email Address\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_3_input_text' aria-label=\"Phone Number\">Phone Number<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Phone Number\" data-name=\"input_text\" id=\"ff_3_input_text\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_3_subject' aria-label=\"Subject\">Subject<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"subject\" class=\"ff-el-form-control\" placeholder=\"Subject\" data-name=\"subject\" id=\"ff_3_subject\"  aria-invalid=\"false\" aria-required=false><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_3_message' aria-label=\"Your Message\">Your Message<\/label><\/div><div class='ff-el-input--content'><textarea aria-invalid=\"false\" aria-required=true name=\"message\" id=\"ff_3_message\" class=\"ff-el-form-control\" placeholder=\"Your Message\" rows=\"4\" cols=\"2\" data-name=\"message\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-center ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style\" >Submit Form<\/button><\/div><\/fieldset><\/form><div id='fluentform_3_errors' class='ff-errors-in-stack ff_form_instance_3_1 ff-form-loading_errors ff_form_instance_3_1_errors'><\/div><\/div>        <script type=\"text\/javascript\">\n            window.fluent_form_ff_form_instance_3_1 = {\"id\":\"3\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_3_1\",\"form_id_selector\":\"fluentform_3\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":true,\"global_message\":\"This field is required\"}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":true,\"global_message\":\"This field is required\"}},\"names[last_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":true,\"global_message\":\"This field is required\"}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":true,\"global_message\":\"This field is required\"},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global\":true,\"global_message\":\"This field must contain a valid email\"}},\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"subject\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":true,\"global_message\":\"This field is required\"}},\"message\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":true,\"global_message\":\"This field is required\"}}},\"debounce_time\":300};\n                    <\/script>\n        \n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-886390324 > .col-inner {\n  padding: 0px 0px 0px 30px;\n  margin: 0px 0px 0px 0px;\n  max-width: 350px;\n}\n@media (min-width:550px) {\n  #col-886390324 > .col-inner {\n    padding: 10px 10px 10px 10px;\n    margin: 0px 10px 0px 100px;\n    max-width: 550px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1623140578\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\n<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d106339.06252987671!2d98.32167426087615!3d7.910832411238646!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x305031bb0cb4020b%3A0xf93416d1fb50bb02!2sPhuket%20world%20pro%20supply%20co.%2CLtd.!5e0!3m2!1sth!2sus!4v1710835756928!5m2!1sth!2sus\" width=\"750\" height=\"550\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_917374785 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(247, 247, 247);\n}\n#section_917374785 .section-bg-overlay {\n  background-color: rgba(255, 255, 255, 0.85);\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Home - Phuketworldprosupply<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/phuketworldprosupply.com\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Phuketworldprosupply\" \/>\n<meta property=\"og:url\" content=\"https:\/\/phuketworldprosupply.com\/\" \/>\n<meta property=\"og:site_name\" content=\"Phuketworldprosupply\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-05T08:29:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/phuketworldprosupply.com\/\",\"url\":\"https:\/\/phuketworldprosupply.com\/\",\"name\":\"Home - Phuketworldprosupply\",\"isPartOf\":{\"@id\":\"https:\/\/phuketworldprosupply.com\/#website\"},\"datePublished\":\"2024-03-15T13:51:14+00:00\",\"dateModified\":\"2024-10-05T08:29:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/phuketworldprosupply.com\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/phuketworldprosupply.com\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/phuketworldprosupply.com\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/phuketworldprosupply.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/phuketworldprosupply.com\/#website\",\"url\":\"https:\/\/phuketworldprosupply.com\/\",\"name\":\"Phuketworldprosupply\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/phuketworldprosupply.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - Phuketworldprosupply","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/phuketworldprosupply.com\/","og_locale":"en_US","og_type":"article","og_title":"Home - Phuketworldprosupply","og_url":"https:\/\/phuketworldprosupply.com\/","og_site_name":"Phuketworldprosupply","article_modified_time":"2024-10-05T08:29:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/phuketworldprosupply.com\/","url":"https:\/\/phuketworldprosupply.com\/","name":"Home - Phuketworldprosupply","isPartOf":{"@id":"https:\/\/phuketworldprosupply.com\/#website"},"datePublished":"2024-03-15T13:51:14+00:00","dateModified":"2024-10-05T08:29:36+00:00","breadcrumb":{"@id":"https:\/\/phuketworldprosupply.com\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/phuketworldprosupply.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/phuketworldprosupply.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/phuketworldprosupply.com\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/phuketworldprosupply.com\/#website","url":"https:\/\/phuketworldprosupply.com\/","name":"Phuketworldprosupply","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/phuketworldprosupply.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/phuketworldprosupply.com\/index.php\/wp-json\/wp\/v2\/pages\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phuketworldprosupply.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/phuketworldprosupply.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/phuketworldprosupply.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/phuketworldprosupply.com\/index.php\/wp-json\/wp\/v2\/comments?post=5"}],"version-history":[{"count":224,"href":"https:\/\/phuketworldprosupply.com\/index.php\/wp-json\/wp\/v2\/pages\/5\/revisions"}],"predecessor-version":[{"id":4540,"href":"https:\/\/phuketworldprosupply.com\/index.php\/wp-json\/wp\/v2\/pages\/5\/revisions\/4540"}],"wp:attachment":[{"href":"https:\/\/phuketworldprosupply.com\/index.php\/wp-json\/wp\/v2\/media?parent=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}